{"id":84304,"date":"2026-06-24T13:00:10","date_gmt":"2026-06-24T13:00:10","guid":{"rendered":"https:\/\/deythere.com\/?p=84304"},"modified":"2026-06-24T10:27:34","modified_gmt":"2026-06-24T10:27:34","slug":"crise-de-financiamento-do-ethereum-cresce-com-debate-da-ethlabs","status":"publish","type":"post","link":"https:\/\/deythere.com\/pt-br\/crise-de-financiamento-do-ethereum-cresce-com-debate-da-ethlabs\/","title":{"rendered":"A crise de financiamento da Ethereum agrava-se \u00e0 medida que a EthLabs entra no debate sobre o staking"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">As preocupa\u00e7\u00f5es com a crise de financiamento do Ethereum se intensificaram depois que o ex-colaborador da Funda\u00e7\u00e3o Ethereum, Trenton Van Epps, alertou que o ecossistema pode enfrentar uma crise de financiamento gradual nos pr\u00f3ximos meses. O alerta desencadeou um debate mais amplo sobre como o Ethereum deve financiar seu desenvolvimento sem comprometer a descentraliza\u00e7\u00e3o. A discuss\u00e3o colocou em destaque uma proposta controversa relacionada \u00e0s recompensas dos validadores, enquanto uma iniciativa sem fins lucrativos chamada EthLabs surgiu como uma alternativa de financiamento.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">O debate n\u00e3o se trata apenas de arrecadar dinheiro, mas tamb\u00e9m de decidir quem deve controlar as decis\u00f5es de financiamento do ecossistema em uma rede descentralizada. \u00c0 medida que o Ethereum entra em uma nova fase de desenvolvimento, a comunidade est\u00e1 dividida entre aqueles que apoiam novos mecanismos de financiamento e aqueles que alertam para mudan\u00e7as que podem alterar os incentivos dos validadores.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">O que est\u00e1 por tr\u00e1s do debate sobre a crise de financiamento do Ethereum?<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">A crise de financiamento do Ethereum refere-se \u00e0s preocupa\u00e7\u00f5es sobre a exist\u00eancia de um modelo confi\u00e1vel de financiamento de longo prazo para pesquisa, infraestrutura e desenvolvimento do ecossistema. A discuss\u00e3o come\u00e7ou depois que Trenton Van Epps alertou que o ecossistema central de desenvolvimento do <a href=\"https:\/\/deythere.com\/ethereum-treasury-strategy-gains-focus-as-bitmine-plans-300m-stock-offering\/\">Ethereum poderia enfrentar<\/a> press\u00e3o financeira dentro de tr\u00eas a nove meses.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Ele apontou o decl\u00ednio de programas de suporte mais antigos e a redu\u00e7\u00e3o dos gastos da Funda\u00e7\u00e3o Ethereum como fatores importantes para suas preocupa\u00e7\u00f5es. Van Epps estimou que manter mais de 10 equipes de clientes, pesquisa e coordena\u00e7\u00e3o custa cerca de US$ 30 milh\u00f5es por ano. Segundo ele, mecanismos existentes, incluindo o Programa de Incentivo a Clientes, podem n\u00e3o ser suficientes para atender \u00e0s crescentes necessidades de desenvolvimento do Ethereum.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">No entanto, o alerta enfrentou forte oposi\u00e7\u00e3o de alguns participantes da comunidade Ethereum. Alguns argumentaram que as reservas atuais da Funda\u00e7\u00e3o podem sustentar as opera\u00e7\u00f5es por um longo per\u00edodo e que a situa\u00e7\u00e3o n\u00e3o representa uma escassez imediata de recursos. O presidente da BitMine, Tom Lee, tamb\u00e9m rejeitou a preocupa\u00e7\u00e3o, afirmando que havia \u201czero chance\u201d de o Ethereum ficar sem recursos para o desenvolvimento do protocolo.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">A pr\u00f3pria pol\u00edtica de tesouraria da Funda\u00e7\u00e3o Ethereum tamb\u00e9m influenciou o debate. Em junho de 2025, a Funda\u00e7\u00e3o anunciou um plano para manter uma reserva operacional equivalente a 2,5 anos em caixa e stablecoins. Tamb\u00e9m planejou limitar os gastos anuais a 15% dos ativos da tesouraria, reduzindo gradualmente esse percentual para uma base de 5% ao longo de cinco anos.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Posteriormente, a Funda\u00e7\u00e3o reduziu seus gastos em cerca de 40% como parte dessa transi\u00e7\u00e3o. Essas mudan\u00e7as aumentaram a press\u00e3o sobre o debate, pois alguns participantes interpretaram o or\u00e7amento reduzido como um sinal de que novas estruturas de financiamento podem ser necess\u00e1rias.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">O que \u00e9 a proposta Validator Redirected Revenue?<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Validator Redirected Revenue \u00e9 uma proposta de pesquisa apresentada por Cl\u00e9ment Lesaege, cofundador da Kleros. A proposta explora se os validadores poderiam redirecionar parte de suas recompensas de staking para financiar o ecossistema Ethereum. Lesaege apresentou a ideia como uma poss\u00edvel solu\u00e7\u00e3o para o problema dos bens p\u00fablicos e dos participantes que se beneficiam sem contribuir financeiramente.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Seu argumento \u00e9 que muitos participantes se beneficiam das melhorias na infraestrutura compartilhada, mas nenhum grupo possui um incentivo forte para financiar esses esfor\u00e7os sozinho. A proposta sugere que os validadores possam indicar uma taxa de redirecionamento entre 0% e 10% das recompensas de staking. Eles tamb\u00e9m poderiam indicar endere\u00e7os benefici\u00e1rios ou formas de divis\u00e3o dos recursos.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Os clientes de execu\u00e7\u00e3o agregariam as prefer\u00eancias dos validadores para determinar como os fundos seriam distribu\u00eddos. A proposta descreve um processo coletivo de decis\u00e3o baseado em m\u00e9todos de agrega\u00e7\u00e3o de prefer\u00eancias semelhantes \u00e0 vota\u00e7\u00e3o do tipo Condorcet. Trata-se de uma proposta em est\u00e1gio de pesquisa publicada no EthResearch, n\u00e3o sendo uma EIP nem uma mudan\u00e7a oficial do protocolo. Atualmente, ela n\u00e3o est\u00e1 ativa nem aprovada.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Qualquer implementa\u00e7\u00e3o exigiria atualiza\u00e7\u00f5es de clientes, coordena\u00e7\u00e3o entre validadores e uma altera\u00e7\u00e3o no protocolo ou um hard fork, criando barreiras t\u00e9cnicas e de governan\u00e7a significativas. A proposta sugere que, se a maioria dos validadores apoiar uma taxa de redirecionamento diferente de zero, o mecanismo poder\u00e1 se tornar obrigat\u00f3rio para toda a rede. Hoje, a taxa permanece em 0%.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Por que os cr\u00edticos chamam a ideia de imposto sobre staking?<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">O debate sobre a crise de financiamento do Ethereum tornou-se mais controverso depois que os opositores passaram a descrever a proposta como um poss\u00edvel \u201cimposto sobre staking\u201d ou \u201cimposto sobre validadores\u201d. Os cr\u00edticos argumentam que o mecanismo pode criar um precedente para redistribui\u00e7\u00e3o em n\u00edvel de protocolo e dar maior influ\u00eancia aos grandes validadores ou operadores de staking sobre as decis\u00f5es de financiamento do ecossistema.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Alguns participantes temem que isso possa confundir os limites entre seguran\u00e7a da rede e governan\u00e7a, transformando validadores em tomadores de decis\u00e3o sobre a aloca\u00e7\u00e3o de recursos financeiros. Os opositores tamb\u00e9m alertaram para riscos de forma\u00e7\u00e3o de cart\u00e9is e poss\u00edveis conflitos entre operadores de validadores e detentores de ETH que delegam seus ativos.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Um provedor de staking pode apoiar uma prefer\u00eancia de financiamento que os delegadores individuais n\u00e3o necessariamente aprovam. A rea\u00e7\u00e3o pol\u00edtica tem sido mais intensa do que o impacto econ\u00f4mico sugerido pelos n\u00fameros. Enquanto os apoiadores afirmam que o valor redirecionado seria limitado, os cr\u00edticos acreditam que o principal problema \u00e9 alterar as recompensas dos validadores por meio de regras do protocolo.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Max Shannon, pesquisador s\u00eanior da Bitwise, observou que a participa\u00e7\u00e3o no staking do Ethereum permaneceu relativamente est\u00e1vel apesar da redu\u00e7\u00e3o das recompensas. Segundo ele, a taxa anual de retorno caiu de cerca de 4,6% em junho de 2023 para aproximadamente 2,7% atualmente, enquanto a quantidade de ETH em staking praticamente dobrou.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">No entanto, Shannon alertou que uma compress\u00e3o ainda maior das recompensas pode aumentar a relev\u00e2ncia dos riscos de slashing e liquidez na fila de sa\u00edda. Ele tamb\u00e9m afirmou que retornos menores podem incentivar validadores a depender mais do valor m\u00e1ximo extra\u00edvel (MEV), levantando preocupa\u00e7\u00f5es adicionais sobre resist\u00eancia \u00e0 censura.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Quanto financiamento as recompensas de validadores poderiam fornecer?<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">A lacuna financeira no centro do debate \u00e9 relativamente pequena quando comparada \u00e0 economia total de staking do Ethereum. Shannon estimou que, se o d\u00e9ficit anual de financiamento for de cerca de US$ 30 milh\u00f5es e as recompensas anuais de staking forem aproximadamente US$ 1,9 bilh\u00e3o, a diferen\u00e7a poderia ser coberta com apenas 1,6% dessas recompensas.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Lesaege estimou que um redirecionamento entre 5% e 10% poderia gerar entre 50.000 e 70.000 ETH por ano para o desenvolvimento do ecossistema. Com base nos pre\u00e7os atuais do ETH mencionados na discuss\u00e3o, isso representaria aproximadamente entre US$ 82,5 milh\u00f5es e US$ 115,5 milh\u00f5es.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">No entanto, a principal diverg\u00eancia n\u00e3o est\u00e1 relacionada ao valor arrecadado. O conflito gira em torno da quest\u00e3o de saber se o Ethereum deve introduzir um mecanismo em n\u00edvel de protocolo que altere a distribui\u00e7\u00e3o da renda proveniente do staking. Os apoiadores consideram a proposta uma ferramenta de coordena\u00e7\u00e3o para financiar bens p\u00fablicos. J\u00e1 os cr\u00edticos acreditam que ela pode criar riscos de governan\u00e7a de longo prazo ao concentrar influ\u00eancia entre grandes validadores.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">A EthLabs pode mudar a abordagem de financiamento do Ethereum?<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">A EthLabs surgiu como outra poss\u00edvel resposta ao debate sobre a crise de financiamento do Ethereum ao criar uma organiza\u00e7\u00e3o sem fins lucrativos focada em pesquisa e desenvolvimento para Ethereum e ETH. A organiza\u00e7\u00e3o foi anunciada por cinco ex-pesquisadores da Funda\u00e7\u00e3o Ethereum e recebeu apoio de participantes importantes do ecossistema, incluindo BitMine, SharpLink e Joseph Lubin, fundador da ConsenSys.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Diferentemente da proposta Validator Redirected Revenue, a EthLabs n\u00e3o exige mudan\u00e7as nas regras do protocolo do Ethereum nem na economia dos validadores. Sua abordagem \u00e9 baseada no apoio institucional direto para pesquisa, infraestrutura e desenvolvimento do ecossistema. A EthLabs afirmou que pretende apoiar o Ethereum como uma camada de liquida\u00e7\u00e3o para a economia global, trabalhando em conjunto com desenvolvedores, equipes de infraestrutura, aplica\u00e7\u00f5es, institui\u00e7\u00f5es e detentores de ETH.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">A organiza\u00e7\u00e3o n\u00e3o substitui a Funda\u00e7\u00e3o Ethereum. Em vez disso, representa um poss\u00edvel modelo de financiamento com m\u00faltiplas organiza\u00e7\u00f5es, no qual diferentes grupos contribuem para diferentes \u00e1reas do desenvolvimento do Ethereum. Lubin afirmou que a Funda\u00e7\u00e3o Ethereum ainda possui talentos significativos focados nos componentes centrais e cypherpunk do protocolo. Ele acrescentou que outras equipes de pesquisa podem explorar \u00e1reas adicionais do desenvolvimento do Ethereum.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">A EthLabs oferece um caminho de financiamento fora do protocolo, mas ainda n\u00e3o est\u00e1 claro se o apoio institucional por si s\u00f3 ser\u00e1 suficiente para sustentar as necessidades de pesquisa de longo prazo do Ethereum. Fontes de financiamento concentradas tamb\u00e9m podem levantar quest\u00f5es sobre influ\u00eancia nas prioridades de pesquisa.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Conclus\u00e3o<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">As discuss\u00f5es sobre a crise de financiamento do Ethereum mostram que o desafio da rede n\u00e3o \u00e9 simplesmente encontrar dinheiro. Trata-se de criar uma estrutura de financiamento que apoie o desenvolvimento enquanto protege os princ\u00edpios descentralizados do Ethereum. A proposta Validator Redirected Revenue continua sendo uma discuss\u00e3o em est\u00e1gio inicial de pesquisa e n\u00e3o alterou as recompensas de staking.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">A proposta gerou debates em toda a comunidade Ethereum, \u00e0 medida que os participantes avaliam preocupa\u00e7\u00f5es relacionadas ao papel dos validadores, influ\u00eancia na governan\u00e7a e necessidade de manter a neutralidade do protocolo. A EthLabs representa uma abordagem diferente ao permitir que organiza\u00e7\u00f5es e grandes apoiadores de ETH financiem o desenvolvimento diretamente.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">O futuro desse modelo de financiamento ainda \u00e9 incerto. Desenvolvedores, validadores, investidores e grupos do ecossistema Ethereum continuar\u00e3o debatendo como financiar o desenvolvimento da rede enquanto mant\u00eam o poder de decis\u00e3o distribu\u00eddo.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Gloss\u00e1rio<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Crise de Financiamento do Ethereum:<\/strong> Quest\u00f5es sobre como financiar o crescimento futuro do Ethereum.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>EthLabs:<\/strong> Uma organiza\u00e7\u00e3o sem fins lucrativos que apoia a pesquisa do Ethereum.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Recompensas de Staking:<\/strong> Ganhos recebidos pelos validadores do Ethereum.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Staking de ETH:<\/strong> Bloqueio de ETH para receber recompensas da rede.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Financiamento de Protocolo:<\/strong> Recursos usados para apoiar o desenvolvimento do Ethereum.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Debate de Governan\u00e7a:<\/strong> Discuss\u00e3o sobre financiamento e tomada de decis\u00f5es no Ethereum.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Perguntas Frequentes Sobre a Crise de Financiamento do Ethereum<\/h2>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>Por que o Ethereum enfrenta preocupa\u00e7\u00f5es com financiamento?<\/strong><\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Alguns participantes temem que os custos futuros de desenvolvimento superem o suporte financeiro atual.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>Por que algumas pessoas chamam a proposta de imposto sobre staking?<\/strong><\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Os cr\u00edticos acreditam que ela redirecionaria parte das recompensas dos validadores para financiar projetos do ecossistema.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>Quanto financiamento a proposta poderia gerar?<\/strong><\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Os apoiadores estimam que ela poderia gerar dezenas de milh\u00f5es de d\u00f3lares por ano.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>A EthLabs pode mudar o modelo de financiamento do Ethereum?<\/strong><\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">A EthLabs pode oferecer uma nova forma de financiar o desenvolvimento do Ethereum por meio de apoio privado.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>A proposta de recompensas de staking foi aprovada?<\/strong><\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">N\u00e3o. A proposta continua em discuss\u00e3o e n\u00e3o faz parte do Ethereum atualmente.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>Fontes:<\/strong><\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/cointelegraph.com\/features\/ethereums-funding-scare-why-a-hated-staking-tax-may-already-be-obsolete\" rel=\"nofollow noopener\" target=\"_blank\">Cointelegraph<\/a><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/ethresear.ch\/t\/validator-redirected-revenue\/25248\" rel=\"nofollow noopener\" target=\"_blank\">ETHresearch<\/a><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/bitcoinist.com\/ethereum-staking-tax-debate-erupts-over-validator-redirected-revenue-proposal\/\" rel=\"nofollow noopener\" target=\"_blank\">Bitcoinist<\/a><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>As preocupa\u00e7\u00f5es com a crise de financiamento do Ethereum se intensificaram depois que o ex-colaborador da Funda\u00e7\u00e3o Ethereum, Trenton Van Epps, alertou que o ecossistema pode enfrentar uma crise de financiamento gradual nos pr\u00f3ximos meses. O alerta desencadeou um debate mais amplo sobre como o Ethereum deve financiar seu desenvolvimento sem comprometer a descentraliza\u00e7\u00e3o. A [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":80864,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[120,121,2],"tags":[1165,10],"ppma_author":[3159],"class_list":["post-84304","post","type-post","status-publish","format-standard","has-post-thumbnail","category-crypto","category-ethereum","category-news","tag-eth","tag-ethereum"],"authors":[{"term_id":3159,"user_id":35,"is_guest":0,"slug":"shravani-dhumal","display_name":"Shravani Dhumal","avatar_url":"https:\/\/deythere.com\/wp-content\/litespeed\/avatar\/c5c3405415992a906290fb9fd4a7d2ae.jpg?ver=1784016972","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/deythere.com\/pt-br\/wp-json\/wp\/v2\/posts\/84304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deythere.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/deythere.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/deythere.com\/pt-br\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/deythere.com\/pt-br\/wp-json\/wp\/v2\/comments?post=84304"}],"version-history":[{"count":2,"href":"https:\/\/deythere.com\/pt-br\/wp-json\/wp\/v2\/posts\/84304\/revisions"}],"predecessor-version":[{"id":84328,"href":"https:\/\/deythere.com\/pt-br\/wp-json\/wp\/v2\/posts\/84304\/revisions\/84328"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/deythere.com\/pt-br\/wp-json\/wp\/v2\/media\/80864"}],"wp:attachment":[{"href":"https:\/\/deythere.com\/pt-br\/wp-json\/wp\/v2\/media?parent=84304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/deythere.com\/pt-br\/wp-json\/wp\/v2\/categories?post=84304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/deythere.com\/pt-br\/wp-json\/wp\/v2\/tags?post=84304"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/deythere.com\/pt-br\/wp-json\/wp\/v2\/ppma_author?post=84304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}